{"id":21155,"date":"2025-01-23T01:50:33","date_gmt":"2025-01-23T06:50:33","guid":{"rendered":"https:\/\/scubapanama.com\/product\/ist-s7-8-bota-titanio-6-5mm-m-8\/"},"modified":"2025-05-09T11:19:15","modified_gmt":"2025-05-09T16:19:15","slug":"ist-s7-8-bota-titanio-6-5mm-m-8","status":"publish","type":"product","link":"https:\/\/scubapanama.com\/es\/product\/ist-s7-8-bota-titanio-6-5mm-m-8\/","title":{"rendered":"IST BOTA TITANIO 6.5MM M \/ 8 (S7 \/ 8)"},"content":{"rendered":"<p><span>\u2022 Botas de neopreno de 5 mm forradas en titanio y elastano con suela de goma vulcanizada<\/span><\/p>\n<p><span>\u2022 Todas las costuras est\u00e1n cosidas a ciegas y pegadas dos veces para evitar la entrada del agua y aumentar la resistencia de la costura.<\/span><\/p>\n<p><span>\u2022 Punteras y talones para mayor soporte y protecci\u00f3n.<\/span><\/p>\n<p><span>\u2022 La abrazadera de la correa de la aleta incorporada ayuda a mantener las correas de la aleta firmemente en su lugar<\/span><\/p>\n<p><span>\u2022 Cremallera YKK ultraduradera n.\u00b0 10 con refuerzo interior para evitar filtraciones<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Botas de neopreno de 5 mm forradas en titanio y elastano con suela de goma vulcanizada.<\/p>\n","protected":false},"featured_media":24228,"comment_status":"open","ping_status":"closed","template":"","meta":{"iawp_total_views":4,"_joinchat":[]},"product_brand":[],"product_cat":[111],"product_tag":[163,218],"class_list":["post-21155","product","type-product","status-publish","has-post-thumbnail","product_cat-tienda-online","product_tag-boot","product_tag-ist-es","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"booking_location":null,"booking_location_type":null,"booking_duration":null,"booking_duration_unit":null,"booking_buffer":null,"booking_cost":null,"booking_resources":null,"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/21155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/comments?post=21155"}],"version-history":[{"count":2,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/21155\/revisions"}],"predecessor-version":[{"id":26067,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/21155\/revisions\/26067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/media\/24228"}],"wp:attachment":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/media?parent=21155"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_brand?post=21155"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_cat?post=21155"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_tag?post=21155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}