{"id":21136,"date":"2025-01-23T01:50:52","date_gmt":"2025-01-23T06:50:52","guid":{"rendered":"https:\/\/scubapanama.com\/product\/s-pearls-cl4-yl-lace-thru-4-lb-amarillo\/"},"modified":"2025-05-15T15:01:51","modified_gmt":"2025-05-15T20:01:51","slug":"s-pearls-cl4-yl-lace-thru-4-lb-amarillo","status":"publish","type":"product","link":"https:\/\/scubapanama.com\/es\/product\/s-pearls-cl4-yl-lace-thru-4-lb-amarillo\/","title":{"rendered":"S.PEARLS LACE-THRU 4 LB AMARILLO (CL4-YL)"},"content":{"rendered":"<h1 id=\"yui_3_17_2_1_1747337956881_149\" class=\"ProductItem-details-title\" data-content-field=\"title\"><span>Recubierto con encaje<\/span><\/h1>\n<div id=\"yui_3_17_2_1_1747337956881_147\" class=\"ProductItem-details-excerpt\" data-content-field=\"excerpt\">\n<p class=\"\"><span>Evite manipular plomo sin recubrimiento con las pesas de plomo recubiertas de vinilo Sea Pearls. El plomo sin recubrimiento puede da\u00f1ar las cubiertas de los barcos y las piscinas. Las pesas de plomo recubiertas de vinilo Sea Pearl protegen estas importantes superficies. Nadie en la industria lo hace mejor. Nuestro recubrimiento de vinilo es resistente y duradero. Resiste rayones y no se despega.<\/span><\/p>\n<ul data-rte-list=\"default\">\n<li>\n<p class=\"\"><span>Protege cubiertas de barcos y piscinas.<\/span><\/p>\n<\/li>\n<li>\n<p class=\"\"><span>Evita que el plomo entre en contacto con tus manos.<\/span><\/p>\n<\/li>\n<li>\n<p class=\"\"><span>El acabado mate resiste rayones y decoloraci\u00f3n.<\/span><\/p>\n<\/li>\n<li>\n<p class=\"\"><span>Ideal para usar con cinturones de peso de nailon o goma.<\/span><\/p>\n<\/li>\n<li>\n<p class=\"\"><span>Ideal para usar en BC con peso integrado<\/span><\/p>\n<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Evite manipular plomo sin recubrimiento con las pesas de plomo recubiertas de vinilo Sea Pearls.<\/p>\n","protected":false},"featured_media":28656,"comment_status":"open","ping_status":"closed","template":"","meta":{"iawp_total_views":0,"_joinchat":[]},"product_brand":[],"product_cat":[111],"product_tag":[268],"class_list":["post-21136","product","type-product","status-publish","has-post-thumbnail","product_cat-tienda-online","product_tag-s-pearls-es","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"booking_location":null,"booking_location_type":null,"booking_duration":null,"booking_duration_unit":null,"booking_buffer":null,"booking_cost":null,"booking_resources":null,"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/21136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/comments?post=21136"}],"version-history":[{"count":2,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/21136\/revisions"}],"predecessor-version":[{"id":28672,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/21136\/revisions\/28672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/media\/28656"}],"wp:attachment":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/media?parent=21136"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_brand?post=21136"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_cat?post=21136"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_tag?post=21136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}