{"id":20787,"date":"2025-01-24T02:00:40","date_gmt":"2025-01-24T07:00:40","guid":{"rendered":"https:\/\/scubapanama.com\/product\/14-6418-50-aleta-viper-ff-ny-xxs-3-4\/"},"modified":"2025-05-13T16:36:15","modified_gmt":"2025-05-13T21:36:15","slug":"14-6418-50-aleta-viper-ff-ny-xxs-3-4","status":"publish","type":"product","link":"https:\/\/scubapanama.com\/es\/product\/14-6418-50-aleta-viper-ff-ny-xxs-3-4\/","title":{"rendered":"OCEANIC ALETA VIPER FF, NY, XXS 3\/4 (14.6418.50)"},"content":{"rendered":"<p><strong><span>R\u00e1pidas y reactivas.<\/span><\/strong><span>\u00a0Las aletas Full Foot Viper 2 est\u00e1n listas para impulsar todas tus aventuras acu\u00e1ticas. Ideales para cualquier nivel, pero con el rendimiento y la est\u00e9tica de un modelo de \u00e9lite, ofrecen una combinaci\u00f3n precisa de hidrodin\u00e1mica para m\u00e1xima comodidad, eficiencia y rendimiento. El canal flexible Power Thrust y los rieles de canal mejorados dirigen el flujo de agua desde las puntas de la aleta, ofreciendo potencia y eficiencia inigualables a un precio excelente. Pero no nos quedamos ah\u00ed. Las nuevas caracter\u00edsticas incluyen una pala pulida y rieles de rendimiento redise\u00f1ados para darle a la Viper 2 una actualizaci\u00f3n muy necesaria. Tambi\u00e9n disponible con dise\u00f1o de tal\u00f3n abierto.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>R\u00e1pidas y reactivas.<\/strong>\u00a0Las aletas Full Foot Viper 2 est\u00e1n listas para impulsar todas tus aventuras acu\u00e1ticas.<\/p>\n","protected":false},"featured_media":23298,"comment_status":"open","ping_status":"closed","template":"","meta":{"iawp_total_views":1,"_joinchat":[]},"product_brand":[],"product_cat":[111],"product_tag":[126],"class_list":["post-20787","product","type-product","status-publish","has-post-thumbnail","product_cat-tienda-online","product_tag-oceanic-es","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"booking_location":null,"booking_location_type":null,"booking_duration":null,"booking_duration_unit":null,"booking_buffer":null,"booking_cost":null,"booking_resources":null,"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/20787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/comments?post=20787"}],"version-history":[{"count":3,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/20787\/revisions"}],"predecessor-version":[{"id":27132,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/20787\/revisions\/27132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/media\/23298"}],"wp:attachment":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/media?parent=20787"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_brand?post=20787"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_cat?post=20787"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_tag?post=20787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}