{"id":20768,"date":"2025-01-24T02:00:41","date_gmt":"2025-01-24T07:00:41","guid":{"rendered":"https:\/\/scubapanama.com\/product\/14-6507-56-oceanic-viper-2-aleta-ff-blk-xl-12-13\/"},"modified":"2025-04-25T10:29:22","modified_gmt":"2025-04-25T15:29:22","slug":"14-6507-56-oceanic-viper-2-aleta-ff-blk-xl-12-13","status":"publish","type":"product","link":"https:\/\/scubapanama.com\/es\/product\/14-6507-56-oceanic-viper-2-aleta-ff-blk-xl-12-13\/","title":{"rendered":"OCEANIC VIPER 2 ALETA FF BLK XL 12-13 (14.6507.56)"},"content":{"rendered":"<p>Las aletas Viper 2 de tal\u00f3n abierto est\u00e1n listas para impulsar todas tus aventuras acu\u00e1ticas. Ideales para cualquier nivel, ofrecen el rendimiento y la est\u00e9tica de un modelo de \u00e9lite. La aleta Viper 2 combina hidrodin\u00e1mica de precisi\u00f3n para m\u00e1xima comodidad, eficiencia y rendimiento. El canal flexible Power Thrust y los rieles de canal mejorados dirigen el flujo de agua hacia las puntas de la aleta, ofreciendo potencia y eficiencia inigualables a un precio excelente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las aletas Viper 2 de tal\u00f3n abierto est\u00e1n listas para impulsar todas tus aventuras acu\u00e1ticas. Ideales para cualquier nivel, ofrecen el rendimiento y la est\u00e9tica de un modelo de \u00e9lite.<\/p>\n","protected":false},"featured_media":23302,"comment_status":"open","ping_status":"closed","template":"","meta":{"iawp_total_views":4,"_joinchat":[]},"product_brand":[],"product_cat":[111],"product_tag":[126],"class_list":["post-20768","product","type-product","status-publish","has-post-thumbnail","product_cat-tienda-online","product_tag-oceanic-es","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"booking_location":null,"booking_location_type":null,"booking_duration":null,"booking_duration_unit":null,"booking_buffer":null,"booking_cost":null,"booking_resources":null,"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/20768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/comments?post=20768"}],"version-history":[{"count":3,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/20768\/revisions"}],"predecessor-version":[{"id":23506,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/20768\/revisions\/23506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/media\/23302"}],"wp:attachment":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/media?parent=20768"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_brand?post=20768"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_cat?post=20768"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_tag?post=20768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}