{"id":20649,"date":"2025-01-23T01:50:57","date_gmt":"2025-01-23T06:50:57","guid":{"rendered":"https:\/\/scubapanama.com\/product\/scubapro-24-156-400-mascara-trinidad-3-naranja\/"},"modified":"2025-04-23T12:04:14","modified_gmt":"2025-04-23T17:04:14","slug":"scubapro-24-156-400-mascara-trinidad-3-naranja","status":"publish","type":"product","link":"https:\/\/scubapanama.com\/es\/product\/scubapro-24-156-400-mascara-trinidad-3-naranja\/","title":{"rendered":"SCUBAPRO M\u00c1SCARA TRINIDAD 3 NARANJA (24.156.400)"},"content":{"rendered":"<p>El Trinidad 3 ofrece el mismo dise\u00f1o popular de lente \u00fanica y una construcci\u00f3n ligera sin montura que el Trinidad 2. La novedad es el dise\u00f1o del sistema de hebillas: las hebillas de liberaci\u00f3n r\u00e1pida se fijan a las leng\u00fcetas del fald\u00f3n para optimizar la libertad de movimiento al ajustar el ajuste. Estas hebillas son compatibles con las nuevas correas Comfort Straps, similares a las de las gafas de esqu\u00ed. Tambi\u00e9n se incluye una emocionante gama de colores vibrantes que combinan con las aletas Seawing Nova y los chalecos hidrost\u00e1ticos HYDRO PRO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Trinidad 3 ofrece el mismo dise\u00f1o popular de lente \u00fanica y una construcci\u00f3n ligera sin montura que el Trinidad 2.<\/p>\n","protected":false},"featured_media":22541,"comment_status":"open","ping_status":"closed","template":"","meta":{"iawp_total_views":0,"_joinchat":[]},"product_brand":[],"product_cat":[111],"product_tag":[153],"class_list":["post-20649","product","type-product","status-publish","has-post-thumbnail","product_cat-tienda-online","product_tag-scubapro-es","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"booking_location":null,"booking_location_type":null,"booking_duration":null,"booking_duration_unit":null,"booking_buffer":null,"booking_cost":null,"booking_resources":null,"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/20649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/comments?post=20649"}],"version-history":[{"count":2,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/20649\/revisions"}],"predecessor-version":[{"id":23143,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product\/20649\/revisions\/23143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/media\/22541"}],"wp:attachment":[{"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/media?parent=20649"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_brand?post=20649"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_cat?post=20649"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/scubapanama.com\/es\/wp-json\/wp\/v2\/product_tag?post=20649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}